{"id":6544,"date":"2018-05-02T11:41:24","date_gmt":"2018-05-02T09:41:24","guid":{"rendered":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/?post_type=evento&#038;p=6544"},"modified":"2018-05-02T15:42:48","modified_gmt":"2018-05-02T13:42:48","slug":"gita-sociale-2018-atene","status":"publish","type":"evento","link":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/","title":{"rendered":"Gita sociale 2018: Atene"},"content":{"rendered":"<p>Tra gli scopi dei Lions primeggia l&#8217;amicizia, rigorosamente con la A maiuscola, senza la quale ogni iniziativa di Club risulterebbe impossibile. Quindi <!--more-->\u00e8 compito di ogni Presidente inserire nel proprio programma sociale iniziative atte a rinsaldare ed accrescere questo legame tra i Soci. Cos\u00ec, come ogni anno, nelle gite di Club, tra goliardia e cultura, l&#8217;amicizia diventa artefice e scopo.<\/p>\n<p>Il Presidente Vincenzo Nuzzi, coadiuvato dal Vice Presidente Vincenzo Nicastro, hanno affidato l&#8217;organizzazione della Gita sociale 2018 alla insostituibile Francesca De Ritis, ormai storica Presidente del Comitato Feste e Gite che, con le capacit\u00e0 di una grande professionista del settore, \u00e8 riuscita anche quest&#8217;anno a stupire i Soci e gli ospiti del Club.<\/p>\n<h1>A fondo pagina\u00a0 ci sono i link alle Gallerie fotografiche.<\/h1>\n<p>Qui di seguito il Programma di viaggio<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">Dolce Atene<\/h2>\n<p>28 Aprile \u2013 01 Maggio 2018<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6584\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0036-1024x669.jpg\" alt=\"\" width=\"1024\" height=\"669\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0036-1024x669.jpg 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0036-300x196.jpg 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0036-768x502.jpg 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0036.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2>Programma Di Viaggio<\/h2>\n<p>\u2022 Sabato 28 Aprile<\/p>\n<p>Ore 5:30 Ritrovo dei partecipanti nel piazzale antistante la Chiesa del Carmine Nuovo (V.le I Maggio).<br \/>\nOre 6:00 Partenza in Pullman GT da Foggia per l\u2019aeroporto Napoli Capodichino.<br \/>\nOre 10:35 Partenza del volo Easyjet EZY4823.<br \/>\nOre 13:20 (ora locale) Arrivo all\u2019aeroporto Eleftherios di Atene.<br \/>\nOre 13:45 Trasferimento in pullman per il Delphi Art Hotel (cat. 3 *) \u2013 Atene.<br \/>\nOre 14:30 Arrivo e sistemazione in Hotel.<br \/>\nPomeriggio libero.<br \/>\nOre 20:00 Cena presso la Trattoria Plaka, Via Kidathineon 16.<\/p>\n<p>\u2022 Domenica 29 Aprile<\/p>\n<p>Ore 7:00 Colazione in Hotel.<br \/>\nOre 7:15 Ritrovo dei partecipanti innanzi l\u2019ingresso dell\u2019Hotel e partenza in pullman per il Porto del Pireo.<br \/>\nOre 8:00 Imbarco e partenza per le Isole del Golfo Saronico. A bordo sar\u00e0 presente una guida che durante la navigazione dar\u00e0 dei cenni storici sulle isole. Le visite sono libere ma, chi preferisce, potr\u00e0 acquistare dei tour guidati sulla stessa motonave. Pranzo a bordo (bevande escluse).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6585\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0037-1024x391.jpg\" alt=\"\" width=\"1024\" height=\"391\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0037-1024x391.jpg 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0037-300x115.jpg 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0037-768x294.jpg 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0037.jpg 1078w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Ore 11:00 &#8211; 12:30. Visita di Hydra<br \/>\n\u00c8 l\u2019isola dei pittori e dei fotografi. Una delle isole pi\u00f9 cosmopolite e preferite dal jet-set internazionale. Aristotele Onassis ne era un assiduo frequentatore, cos\u00ec come Mick Jagger, Leonard Cohen ed Henry Miller.<br \/>\nAcque cristalline, architettura unica, arte orafa ed artigianato splendidi. Una piccola isola di fronte al Peloponneso completamente car-free. Qui gli asinelli sono ancora l\u2019unico mezzo di trasporto consentito, oltre la bicicletta.<br \/>\nOre 13:30 &#8211; 14:20. Visita di Poros<br \/>\nUn\u2019isola di soli 48 chilometri quadrati, ricca di vegetazione, ricoperta di pini e di alberi di limoni, con le sue stradine strette ed il campanile dal quale si ha una splendida vista panoramica.<\/p>\n<p>Ore 15:30 &#8211; 18:00. Visita di Aegina<br \/>\nIl suo nome deriva da quello di una principessa, Aegina, di cui, secondo la mitologia greca, s\u2019innamor\u00f2 perdutamente Zeus. Dal loro amore nacque Eaco, il primo re dell\u2019isola.<br \/>\nRicca di storia e di paesaggi straordinari con i suoi famosi alberi di pistacchio, il coloratissimo mercato ortofrutticolo galleggiante, il pittoresco porticciolo di Agia Marina, \u00e8 rinomata per l\u2019ospitalit\u00e0 dei suoi abitanti.<br \/>\nChi vorr\u00e0, potr\u00e0 visitare la chiesa bizantina di Agios Nektarios, che custodisce l\u2019urna decorata in argento con le reliquie del Santo, ed il tempio dorico di Afaia, il pi\u00f9 intatto tra gli antichi templi greci, che offre una magnifica vista sul mare.<br \/>\nOre 19:30 Rientro al Porto del Pireo. Trasferimento in Pullman per l\u2019Hotel.<br \/>\nOre 20:30 Cena in Hotel.<\/p>\n<p>&nbsp;<\/p>\n<p>\u2022 Lunedi 30 Aprile<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6586\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0035-1024x241.jpg\" alt=\"\" width=\"1024\" height=\"241\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0035-1024x241.jpg 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0035-300x71.jpg 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0035-768x181.jpg 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0035.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<hr \/>\n<p>Ore 8:00 Colazione in Hotel.<br \/>\nOre 8:45 Raduno dei partecipanti innanzi l\u2019ingresso dell\u2019Hotel.<br \/>\nOre 9:00 Partenza in pullman per la visita guidata di Atene (circa tre ore).<br \/>\n\u00c8 previsto un giro panoramico della citt\u00e0 di Atene passando davanti ai monumenti ed alle piazze principali: Piazza della Costituzione, Palazzo del Parlamento, Milite Ignoto, Biblioteca Nazionale, Piazza Omonia, Arco di Adriano. Durante il giro si scender\u00e0 dal Bus in prossimit\u00e0 di alcuni luoghi come il Parlamento, proprio in coincidenza con il cambio della guardia, e lo Stadio Panathinaiko, per ammirare esternamente questa bellissima struttura in cui si sono tenuti i moderni giochi olimpici. Infine, si salir\u00e0 sull\u2019Acropoli. Sono esclusi dalla quota gli ingressi, facoltativi, nei vari siti.<br \/>\nPranzo libero.<br \/>\nPomeriggio libero.<br \/>\nOre 20:30 Cena presso la Trattoria Geros Tou Moria, Mnisikleous 27.<\/p>\n<p>&nbsp;<\/p>\n<p>\u2022 Marted\u00ec 01 Maggio<\/p>\n<p>Ore 8:30 Colazione in Hotel.<br \/>\nOre 10:30 Ritrovo dei partecipanti innanzi l\u2019ingresso dell\u2019Hotel.<br \/>\nOre 11:00 Partenza in pullman per l\u2019aeroporto Eleftherios di Atene.<br \/>\nOre 14:00 Partenza del volo Easyjet EZY4824.<br \/>\nOre 14:45 (ora locale) Arrivo all\u2019aeroporto Capodichino di Napoli. Sosta per un caff\u00e8 a Napoli e partenza in pullman GT per Foggia.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6588\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_155232-1024x707.png\" alt=\"\" width=\"1024\" height=\"707\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_155232-1024x707.png 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_155232-300x207.png 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_155232-768x530.png 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_155232.png 1703w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Il Fascino di una Citt\u00e0 Distinta<\/p>\n<p>Oggettivamente definita casa della democrazia, del teatro &#8211; che ha raggiunto vette altissime &#8211; e di Socrate, che vi ha concepito le basi della filosofia occidentale, Atene \u00e8 costantemente abitata fin dall\u2019et\u00e0 neolitica. Ma \u00e8 il V secolo il momento della sua massima fioritura, quando \u00e8 diventata la terra madre della nostra civilt\u00e0. La citt\u00e0, che oggi ospita pi\u00f9 di 4 milioni di abitanti, \u00e8 stata costruita attorno al suo cuore antico: l\u2019Acropoli. Quasi tutti i luoghi di interesse sono concentrati vicino Piazza Sintagma, delimitata dai quartieri della Plaka a sud, di Omonia a nord e Monastiraki al centro. Da qualunque lato ci si trovi, lo sguardo si posa sempre sull\u2019Acropoli.<\/p>\n<p>&nbsp;<\/p>\n<h2>Itinerari proposti:<\/h2>\n<p>1 &#8211; Passeggiando nella Storia Antica<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6607\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0029-2-1024x614.jpg\" alt=\"\" width=\"1024\" height=\"614\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0029-2-1024x614.jpg 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0029-2-300x180.jpg 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0029-2-768x461.jpg 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0029-2.jpg 1357w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Piazza Omonia: punto di transito quasi obbligato. Una volta era un luogo davvero bello, come raccontano le vecchie foto di quei giorni di gloria esposte nella stazione della metropolitana. Nella vicina via 28is Oktovriou si trova il Politecnico, simbolo della resistenza di Atene perch\u00e9 ha visto esplodere le dimostrazioni studentesche nel novembre 1973 che determinarono la fine della dittatura.<\/p>\n<p>Monastiraki: \u00e8 stato il centro commerciale della citt\u00e0 durante i 400 anni di dominio ottomano e per questo conserva ancora molto di quel caratteristico stile orientale. Quartiere folcloristico e animato, \u00e8 qui che si svolge tutte le domeniche il mercatino delle pulci.<br \/>\nChi vuole, pu\u00f2 fermarsi al Six d.o.g.s in Odos Avramiotou 6-8, un pub caratteristico immerso in una sorta di cortile alberato su pi\u00f9 livelli. Arredi, luci, grafica dei menu, persino i bicchieri, tutto \u00e8 curato nel dettaglio. Il risultato \u00e8 un locale di qualit\u00e0, frequentato prevalentemente da Greci oltre che da qualche turista che si \u00e8 perso tra le strade affollate di Monastiraki.<\/p>\n<p>Agor\u00e0: il luogo in cui pulsava la vita sociale dell\u2019antica citt\u00e0. Proprio qui sorgeva, duemila anni fa, il primo centro commerciale e sempre qui si radunavano gli abitanti per molte delle attivit\u00e0 quotidiane tra cui elezioni, parate e riti. Qui Socrate passeggiava parlando di filosofia e in questo stesso luogo sub\u00ec la condanna a morte, nel 399 a.C. Accusato di corrompere i giovani per mettere in discussione tutto ci\u00f2 che si voleva far credere verit\u00e0 assoluta, una giuria composta da 501 Ateniesi ascolt\u00f2 la sua difesa basata sul mettere in dubbio le basi del processo stesso. Condannato a morte, si uccise, come tutti ricorderanno, avvelenandosi con la cicuta. Al tempo la piazza era ornata da sculture, monumenti e fontane. Oggi restano solo alcune rovine ma, per rendersi conto dell\u2019importanza del luogo, basta guardare lo Sto\u00e0 di Attalo, cos\u00ec chiamato in onore del re di Pergamo, Attalo, che volle questo lungo edificio. Costituito da portici coperti da un lato e spazi aperti dall\u2019altro, pu\u00f2 definirsi il precursore delle moderne gallerie commerciali. Ecco perch\u00e9 si dice che questo sia stato il primo centro commerciale al mondo con i suoi 40 piccoli negozi.<\/p>\n<p>Acropoli: significa citt\u00e0 alta, domina lo skyline della citt\u00e0 ed \u00e8 il centro di qualunque itinerario turistico nella capitale greca. Su questo sperone roccioso \u00e8 sorto il primo insediamento di Atene. Principale artefice pu\u00f2 considerarsi Pericle (non a caso Tucidide, storico suo contemporaneo, lo acclam\u00f2 &#8220;primo cittadino di Atene\u201d) il quale, con il suo ambizioso programma edilizio, si impose di promuovere l\u2019immagine dello stato ateniese. Verso il 1450 i Turchi trasformarono il Partenone in una moschea e, successivamente, in un deposito di polvere da sparo. Un generale veneziano, pur di mandarli via, non esit\u00f2 a sparare cannonate sull\u2019Acropoli ed una di queste fece saltare in aria il Partenone. Le sculture furono rovinate pesantemente, molte caddero ed i loro pezzi furono presi come souvenir. Nel 1800 l&#8217;ambasciatore britannico di Costantinopoli ottenne la concessione dal Sultano per realizzare disegni sull&#8217;Acropoli e per demolire, se necessario, gli edifici pi\u00f9 recenti con lo scopo di trovare altre antichit\u00e0. Non solo, il diplomatico ebbe il permesso di rimuovere persino alcune sculture, e questa concessione fu interpretata come quella di poter prendere tutte le opere che avrebbe trovato. Assunse gente del luogo per staccare le metope (pannelli di marmo) dalla costruzione stessa e da terra. Attualmente il Partenone e l\u2019Eretteo sono gli unici monumenti rimasti sulla spianata mentre il nuovo Museo dell&#8217;Acropoli ne conserva alcuni frammenti. Altre parti sono esposte al British Museum e al Museo del Louvre.<\/p>\n<p>Plaka: si trova sulle pendici dell\u2019Acropoli e rappresenta il volto pi\u00f9 antico di Atene. Abitata costantemente da quasi 7000 anni, rispetto agli altri quartieri non \u00e8 mai stata stravolta dagli scavi. \u00c8 il luogo dei ristoranti e dei negozi turistici e la maggior parte delle vie sono chiuse al traffico. Le caffetterie sono generalmente carissime se si trovano sulle strade principali, via Kydatheneon e via Adrianou, ma molto spesso eccezionali per la vista che offrono. La Plaka \u00e8 un luogo dalle vie strettissime, dalle piazzette con le case color pastello ricoperte di bouganville che evocano le isole del Dodecanneso. Proprio in queste stradine si celano monumenti, palazzi e chiese bizantine che si affiancano a negozi e ristoranti, creando un ambiente in cui convivono armoniosamente presente e passato, bellezza e funzionalit\u00e0, cultura e divertimenti. Tra le chiese bizantine, la Rangabas \u00e8 una delle pi\u00f9 belle della citt\u00e0. Costruita nell\u2019XI secolo, era il centro della Plaka che si svilupp\u00f2 proprio a partire da essa. La Metochi Panaghiou Tafou, invece, risale al periodo ottomano ed \u00e8 una delle chiese pi\u00f9 famose di Atene perch\u00e9 meta della processione del Venerd\u00ec Santo. In ultimo, il Monumento di Lisicrate, l\u2019esempio meglio conservato di opera coregica, cio\u00e8 i tempietti con cui venivano commemorati i coreghi, i ricchi ateniesi che patrocinavano gli spettacoli teatrali.<\/p>\n<p>Tempio di Zeus: la grandezza di Atene non si discute, si ammira. Questo vale soprattutto quando si osserva il tempio dedicato a Zeus, l\u2019Olympeion, che nell\u2019epoca ellenistica risultava il pi\u00f9 grande di tutta la Grecia. La costruzione risale al VI secolo a.C. ma \u00e8 stata completata solo nel II secolo d.C. dall\u2019Imperatore Adriano. Ancora oggi \u00e8 facile immaginare la grande soggezione che questa struttura potesse incutere nella sua forma iniziale. Totalmente in marmo, con una lunghezza di 96 metri, una larghezza di 40 metri e ben 17 metri di altezza, attualmente ne resta ben poco.<\/p>\n<p>Anafiotika: cos\u00ec \u00e8 chiamato un piccolo gruppo di case a ridosso dell&#8217;Acropoli e poco sopra la Plaka. La zona prende il nome dai suoi primi abitanti, i muratori dell&#8217;isola di Anafi, celebri per la loro bravura e spediti nel 1830, dopo la rivoluzione greca, per ricostruire la citt\u00e0. Definita un&#8217;isola nella citt\u00e0, qui pare di essere nelle Cicladi: le case basse e bianche con le porte blu, scalette, viuzze e piccole chiese. \u00c8 facile immaginare come fosse Atene quando era il centro del mondo ma con la pacifica vita di un borgo sul mare. La sera Anafiotika assume un fascino tutto diverso offrendo un panorama singolare su un\u2019Atene tutta illuminata.<\/p>\n<p>&nbsp;<\/p>\n<p>2 &#8211; Passeggiando nella Storia Moderna<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6606\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_190855-1024x619.jpg\" alt=\"\" width=\"1024\" height=\"619\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_190855-1024x619.jpg 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_190855-300x181.jpg 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_190855-768x464.jpg 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_190855.jpg 1299w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Piazza Sintagma, che significa della costituzione, ha una storia lunga; pare che ogni evento principale della Grecia moderna si sia celebrato qui. Vi si trova il Parlamento e di fronte il monumento dedicato al Milite Ignoto con il famoso cambio della guardia degli Euzoni.<\/p>\n<p>Il Giardino Nazionale, nel passato accessibile soltanto alla famiglia reale, oggi \u00e8 aperto al pubblico. L\u2019ingresso si trova proprio davanti Piazza Sintagma.<\/p>\n<p>Lo Stadio Pantatenaico ha ospitato nel 330 a.C. i Giochi Pantatenaici e, nel 1895, la prima edizione moderna dei Giochi Olimpici.<\/p>\n<p>&nbsp;<\/p>\n<p>3 &#8211; I Musei pi\u00f9 Importanti di Atene<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6605\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_190946-1-1024x620.jpg\" alt=\"\" width=\"1024\" height=\"620\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_190946-1-1024x620.jpg 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_190946-1-300x182.jpg 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_190946-1-768x465.jpg 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_190946-1.jpg 1256w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Il Museo Archeologico Nazionale \u00e8 uno dei pi\u00f9 importanti al mondo. Nonostante le numerose spoliazioni subite dalla Grecia da parte degli archeologi stranieri nell\u2019Ottocento, questo museo vanta tuttora la pi\u00f9 bella raccolta di antichit\u00e0 elleniche.<\/p>\n<p>Il Museo Bizantino esibisce una notevole e preziosa collezione sulla civilt\u00e0 del periodo bizantino tra cui una biblioteca di circa quindicimila volumi dedicata all&#8217;arte, alla letteratura, all&#8217;architettura ed alle istituzioni dell&#8217;Impero d\u2019Oriente.<\/p>\n<p>Il Nuovo Museo dell\u2019Acropoli, aperto nel giugno 2009 proprio ai piedi dell\u2019Acropoli, raccoglie tutti i frammenti del fregio del Partenone in possesso del governo greco in uno spazio architettonico ricostruito con le esatte dimensioni del monumento stesso.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Mare ad Atene<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6601\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191226-1024x594.jpg\" alt=\"\" width=\"1024\" height=\"594\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191226-1024x594.jpg 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191226-300x174.jpg 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191226-768x446.jpg 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191226.jpg 1335w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Glyfada, la localit\u00e0 balneare pi\u00f9 nota, \u00e8 totalmente diversa dalla citt\u00e0 di Atene. Internazionale e ricca, \u00e8 qui che si respira la nuova aria cosmopolita dove il lusso \u00e8 visibile a tutti ed inarrivabile per molti. Negozi eleganti, bar e discoteche, locali modaioli strapieni di giovent\u00f9 bella e abbronzata.<\/p>\n<p>&nbsp;<\/p>\n<p>Lo Shopping ad Atene<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6595\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG_1525007618518.jpg\" alt=\"\" width=\"712\" height=\"730\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG_1525007618518.jpg 712w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG_1525007618518-293x300.jpg 293w\" sizes=\"auto, (max-width: 712px) 100vw, 712px\" \/><\/p>\n<p>Via Ermou, decisamente la strada pi\u00f9 fashion di tutta la capitale greca. In questa via non esistono orari, c\u2019\u00e8 sempre tantissima gente a qualsiasi ora del giorno e della notte sia per gli acquisti che per il gran numero di turisti che la affollano.<\/p>\n<p>Collegato alla via Ermou, Monastiraki rappresenta il suo esatto opposto: un vecchio mercato turco che offre ai turisti la possibilit\u00e0 di scatenarsi nell\u2019acquisto di souvenir di qualsiasi tipo.<\/p>\n<p>&nbsp;<\/p>\n<p>Atene di Notte<\/p>\n<p style=\"padding-left: 30px;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6603\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191036-1024x574.jpg\" alt=\"\" width=\"1024\" height=\"574\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191036-1024x574.jpg 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191036-300x168.jpg 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191036-768x430.jpg 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191036.jpg 1419w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Exarchia, con la sua piazza rumorosa e frequentatissima, \u00e8 il luogo di ritrovo degli studenti universitari per l\u2019intensa vita notturna. La particolarit\u00e0 di questo quartiere \u00e8 che gli edifici sono completamente ricoperti di graffiti, quasi fossero delle tele. Andarci equivale a fare una passeggiata all\u2019aperto in una galleria davvero unica, non a caso alcuni dei suoi artisti di strada hanno ottenuto riconoscimenti in tutto il mondo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6600\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191110-1024x705.jpg\" alt=\"\" width=\"1024\" height=\"705\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191110-1024x705.jpg 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191110-300x206.jpg 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191110-768x529.jpg 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191110.jpg 1078w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Metaxourgeio. Se in passato era considerato un quartiere piuttosto losco, oggi si presenta con un abito completamente diverso. Accoglie gallerie d\u2019arte, musei, ristoranti e caff\u00e8.<\/p>\n<p>Gazi prende il nome dalla vecchia centrale del gas. Inizialmente questo quartiere ospitava un grande deposito di gas naturale ma poich\u00e9 Atene si preparava a diventare sempre pi\u00f9 cosmopolita, nel 1984 l\u2019infrastruttura fu spostata fuori citt\u00e0. Rimasta vuota, l\u2019intera propriet\u00e0 fu trasformata nel cuore della vita notturna di Atene. Oggi Gazi \u00e8 il quartiere pi\u00f9 cool della citt\u00e0, amato dai giovani mentre gli antichi serbatoi del gas, le officine e gli impianti sono diventati la sede di mostre ed eventi culturali.<\/p>\n<p>&nbsp;<\/p>\n<p>I Nostri Ristoranti<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6602\" src=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191157-1024x614.jpg\" alt=\"\" width=\"1024\" height=\"614\" srcset=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191157-1024x614.jpg 1024w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191157-300x180.jpg 300w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191157-768x460.jpg 768w, https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/20180429_191157.jpg 1273w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Sabato 28. Ore 20:00 cena presso Trattoria La Plaka, Via Kidathineon 16<br \/>\nDomenica 29. Ore 20:30 cena in Hotel, Delphi Art Atene<br \/>\nLunedi 30. Ore 20:30 cena presso Trattoria Geros Tou Moria, Mnisikleous 27<\/p>\n<p>&nbsp;<\/p>\n<p>La Tradizione Greca a Tavola<\/p>\n<p>In Grecia il pasto inizia con le meze, un vero e proprio rito che gli Ateniesi non fanno mai mancare sulla propria tavola. Secondo la cultura greca, non si beve mai niente di alcolico che non venga accompagnato con qualcosa da mangiare. Da qui nasce la consuetudine delle meze, piccole porzioni di cibo: tzatziki, souvlaki, mussaka, choriatiki salata (l\u2019insalata greca per eccellenza), keftedes (polpettine fritte di carne, di legumi o di ortaggi).<\/p>\n<p>Tra i formaggi padroneggia l\u2019onnipresente Feta con le sue diverse stagionature.<\/p>\n<p>Nella pasticceria greca domina la pasta fillo, una sorta di pasta sfoglia. Vedere i pasticcieri alle prese con questo impasto diventa quasi un&#8217;esperienza: la sfoglia deve essere tirata al limite e per maneggiarla i maestri devono farla roteare rapidamente. La sua lavorazione \u00e8 un vero spettacolo che si pu\u00f2 osservare, per esempio, al Bougatsadiko, un bar vicino Monastiraki. Con questa pasta si prepara il baklava (con miele e frutta secca) e la bougatsa (una torta con crema pasticcera cotta nel forno). Un altro dolce tipico \u00e8 il loukoumade, una ciambella fritta nell&#8217;olio di sesamo aromatizzata con il miele (immancabile in quasi tutte le preparazioni dolci), cannella e noci. Ancora, lo spoon sweet, frutta bollita in acqua e zucchero offerta insieme allo yogurt. A proposito di yogurt, non manca mai a fine pasto.<\/p>\n<p>Tra i vini bianchi primeggia la Retsina, un resinato secco ed il Boutari, pi\u00f9 fruttato; tra i vini rosati il Kokkineli, resinato secco; tra i vini rossi il Mantineia, il Naoussa, il Nemea, il Rapsani ed il famoso Agiorgitiko.<\/p>\n<p>Tra i superalcolici si distingue l\u2019Ouzo, usato per accompagnare le meze. Diffusissimo, si pu\u00f2 consumare liscio o con ghiaccio. Anche il Brandy \u00e8 molto buono, specie il Metaxa, le cui stellette indicano gli anni di invecchiamento. Lo Tsipouro, invece, \u00e8 simile alla grappa italiana mentre il Rak\u00ec \u00e8 un distillato leggermente pi\u00f9 morbido e fruttato. In ultimo, la Masticha \u00e8 un digestivo dal sapore dolce prodotto dalla resina degli alberi di lentisco.<\/p>\n<p>Espressioni Utili e Traduzione dei Principali Alimenti<\/p>\n<p>Formule di cortesia<br \/>\nCiao\/arrivederci Y\u00e1sas<br \/>\nBuongiorno Kalim\u00e9ra<br \/>\nBuon pomeriggio Kalisp\u00e9ra<br \/>\nBuonasera Kalin\u00edjta<br \/>\nArrivederci Ant\u00edo<br \/>\nSi Kai<br \/>\nNo Oji<br \/>\nPer favore Parakal\u00f3<br \/>\nGrazie Efjarist\u00f3<br \/>\nDi nulla T\u00edpota<br \/>\nScusa Signomi<\/p>\n<p>Al ristorante<br \/>\nAperitivo Oreftik\u00e1<br \/>\nGelato Pagot\u00f3<br \/>\nLatte G\u00e1la<br \/>\nT\u00e8 Ch\u00e1i<br \/>\nArrosto Psit\u00f3<br \/>\nCotto Brast\u00f3<br \/>\nAlla brace Sta c\u00e1rbuna<br \/>\nFritto Tiganit\u00f3<br \/>\nSale Al\u00e1ti<br \/>\nPepe Pip\u00e9ri<br \/>\nOrigano R\u00edgani<br \/>\nCipolla Crem\u00eddi<br \/>\nAglio Sk\u00f3rdo<br \/>\nPane Psom\u00ed<br \/>\nGamberi Gar\u00eddes<br \/>\nVerdura Lajanik\u00e1<br \/>\nPesce Ps\u00e1ri<br \/>\nAgnello Arn\u00e1ki<br \/>\nPollo Kot\u00f3pulo<br \/>\nMaiale Girin\u00f3<br \/>\nVitello Mosj\u00e1ri<br \/>\nCarne Cr\u00e9as<br \/>\nIl conto To logariasm\u00f3<br \/>\nMelone Pep\u00f3ni<br \/>\nAnguria Carpusi<br \/>\nSenza Glutine Cor\u00ecs glut\u00e8ni<\/p>\n<p>&nbsp;<\/p>\n<p>_______________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p>La grande scrittrice francese Marguerite Yourcenar una volta scrisse: \u201c\u2026\u00e8 vano sperare, per Atene e per Roma, quell\u2019eternit\u00e0 che non \u00e8 accordata n\u00e9 agli uomini e n\u00e9 alle cose, e che i pi\u00f9 saggi tra noi negano persino agli dei\u201d.<br \/>\nEppure quando metti piede ad Atene, quando vedi il primo sole tramontare tra la colonna del Partenone e scomparire alle spalle dell\u2019Acropoli, quando ascolti il primo musicista di strada intonare una vecchia e malinconica melodia, e quando i profumi della Plaka, e, in lontananza, i colori del Pireo sconfinano nell\u2019immaginazione tutto sembra trasmettere un concetto astratto, ma efficace, di interminabile immortalit\u00e0.<br \/>\nFilippo Gherardi<\/p>\n<p style=\"padding-left: 120px;\">\u0391\u03bd\u03c4\u03af\u03bf \u03c3\u03b5 \u03cc\u03bb\u03bf\u03c5\u03c2<br \/>\n(Ant\u00edo se \u00f3lous)<\/p>\n","protected":false},"author":36,"featured_media":6584,"comment_status":"open","ping_status":"closed","template":"","categories":[74],"tags":[],"class_list":["post-6544","evento","type-evento","status-publish","has-post-thumbnail","hentry","category-gita-sociale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gita sociale 2018: Atene - LIONS Club Foggia - Umberto Giordano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gita sociale 2018: Atene - LIONS Club Foggia - Umberto Giordano\" \/>\n<meta property=\"og:description\" content=\"Tra gli scopi dei Lions primeggia l&#8217;amicizia, rigorosamente con la A maiuscola, senza la quale ogni iniziativa di Club risulterebbe impossibile. Quindi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/\" \/>\n<meta property=\"og:site_name\" content=\"LIONS Club Foggia - Umberto Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Lions-Club-Foggia-Umberto-Giordano-115119205182578\/?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-02T13:42:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0036.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/evento\\\/gita-sociale-2018-atene\\\/\",\"url\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/evento\\\/gita-sociale-2018-atene\\\/\",\"name\":\"Gita sociale 2018: Atene - LIONS Club Foggia - Umberto Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/evento\\\/gita-sociale-2018-atene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/evento\\\/gita-sociale-2018-atene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/IMG-20180429-WA0036.jpg\",\"datePublished\":\"2018-05-02T09:41:24+00:00\",\"dateModified\":\"2018-05-02T13:42:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/evento\\\/gita-sociale-2018-atene\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/evento\\\/gita-sociale-2018-atene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/evento\\\/gita-sociale-2018-atene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/IMG-20180429-WA0036.jpg\",\"contentUrl\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/IMG-20180429-WA0036.jpg\",\"width\":1080,\"height\":706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/evento\\\/gita-sociale-2018-atene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/evento\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gita sociale 2018: Atene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/#website\",\"url\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/\",\"name\":\"LIONS Club Foggia - Umberto Giordano\",\"description\":\"We Serve\",\"publisher\":{\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/#organization\",\"name\":\"LIONS Club Umberto Giordano\",\"url\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"LIONS Club Umberto Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/lionsclubfoggia.it\\\/umbertogiordano\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Lions-Club-Foggia-Umberto-Giordano-115119205182578\\\/?fref=ts\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gita sociale 2018: Atene - LIONS Club Foggia - Umberto Giordano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/","og_locale":"it_IT","og_type":"article","og_title":"Gita sociale 2018: Atene - LIONS Club Foggia - Umberto Giordano","og_description":"Tra gli scopi dei Lions primeggia l&#8217;amicizia, rigorosamente con la A maiuscola, senza la quale ogni iniziativa di Club risulterebbe impossibile. Quindi","og_url":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/","og_site_name":"LIONS Club Foggia - Umberto Giordano","article_publisher":"https:\/\/www.facebook.com\/Lions-Club-Foggia-Umberto-Giordano-115119205182578\/?fref=ts","article_modified_time":"2018-05-02T13:42:48+00:00","og_image":[{"width":1080,"height":706,"url":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0036.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/","url":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/","name":"Gita sociale 2018: Atene - LIONS Club Foggia - Umberto Giordano","isPartOf":{"@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/#primaryimage"},"image":{"@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/#primaryimage"},"thumbnailUrl":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0036.jpg","datePublished":"2018-05-02T09:41:24+00:00","dateModified":"2018-05-02T13:42:48+00:00","breadcrumb":{"@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/#primaryimage","url":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0036.jpg","contentUrl":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-content\/uploads\/2018\/04\/IMG-20180429-WA0036.jpg","width":1080,"height":706},{"@type":"BreadcrumbList","@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/gita-sociale-2018-atene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/evento\/"},{"@type":"ListItem","position":3,"name":"Gita sociale 2018: Atene"}]},{"@type":"WebSite","@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/#website","url":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/","name":"LIONS Club Foggia - Umberto Giordano","description":"We Serve","publisher":{"@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/#organization","name":"LIONS Club Umberto Giordano","url":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"LIONS Club Umberto Giordano"},"image":{"@id":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Lions-Club-Foggia-Umberto-Giordano-115119205182578\/?fref=ts"]}]}},"_links":{"self":[{"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/evento\/6544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/types\/evento"}],"author":[{"embeddable":true,"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/comments?post=6544"}],"version-history":[{"count":33,"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/evento\/6544\/revisions"}],"predecessor-version":[{"id":6695,"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/evento\/6544\/revisions\/6695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/media\/6584"}],"wp:attachment":[{"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/media?parent=6544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/categories?post=6544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lionsclubfoggia.it\/umbertogiordano\/wp-json\/wp\/v2\/tags?post=6544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}